{"id":2845,"date":"2024-11-24T13:07:20","date_gmt":"2024-11-24T12:07:20","guid":{"rendered":"https:\/\/www.denhandwierker.lu\/?page_id=2845"},"modified":"2024-11-25T18:25:04","modified_gmt":"2024-11-25T17:25:04","slug":"dienste-3","status":"publish","type":"page","link":"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/","title":{"rendered":"Dienste"},"content":{"rendered":"[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;advanced&#8220; gradient_type=&#8220;default&#8220;][nectar_responsive_text inherited_font_style=&#8220;h2&#8243; text_color=&#8220;#424242&#8243; text_direction=&#8220;default&#8220; font_size_phone=&#8220;30&#8243; font_size_desktop=&#8220;50&#8243; font_size_tablet=&#8220;40&#8243;]\n<h2 style=\"text-align: center;\">Unsere Dienstleistungen<\/h2>\n[\/nectar_responsive_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; bottom_padding=&#8220;5%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;hidden&#8220; id=&#8220;menuiserie&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; translate_x=&#8220;100&#8243; translate_x_tablet=&#8220;0&#8243; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;0px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;468&#8243; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; background_image_loading=&#8220;lazy-load&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;relative&#8220; advanced_gradient_angle=&#8220;180&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;advanced&#8220; advanced_gradient_display_type=&#8220;linear&#8220; column_padding_type=&#8220;default&#8220; offset=&#8220;vc_hidden-sm vc_hidden-xs&#8220;][\/vc_column][vc_column top_padding_desktop=&#8220;4vw&#8220; bottom_padding_desktop=&#8220;6vw&#8220; left_padding_desktop=&#8220;7vw&#8220; constrain_group_101=&#8220;yes&#8220; right_padding_desktop=&#8220;7vw&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.8&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;advanced&#8220;][vc_row_inner column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; top_padding=&#8220;10%&#8220; left_padding_desktop=&#8220;2%&#8220; right_padding_desktop=&#8220;10%&#8220; top_padding_tablet=&#8220;8%&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;0px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; mobile_disable_entrance_animation=&#8220;true&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220; delay=&#8220;900&#8243;][image_with_animation image_url=&#8220;2586&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][vc_column_text css=&#8220;.vc_custom_1732387700234{margin-left: 35px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h3 style=\"text-align: center;\">Innen- und Au\u00dfenschreinerei<\/h3>\n<p>Von der Herstellung einer T\u00fcr bis zum Verlegen von Parkett, vom Bau eines Schrankes bis zum Bau eines Carports, eines Standes oder einer Terrasse,<br \/>\nDen mobile Handwierker f\u00fchrt alle Tischlerarbeiten (Neubau oder Renovierung) aus, sowohl f\u00fcr den Innen- als auch f\u00fcr den Au\u00dfenbereich.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; bottom_padding=&#8220;5%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;hidden&#8220; id=&#8220;serrurerie&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column top_padding_desktop=&#8220;4vw&#8220; bottom_padding_desktop=&#8220;6vw&#8220; left_padding_desktop=&#8220;7vw&#8220; constrain_group_101=&#8220;yes&#8220; right_padding_desktop=&#8220;7vw&#8220; top_padding_phone=&#8220;5vw&#8220; top_margin_tablet=&#8220;200&#8243; translate_y=&#8220;-135&#8243; translate_y_tablet=&#8220;200&#8243; translate_y_phone=&#8220;0&#8243; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;50px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.8&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;advanced&#8220;][divider line_type=&#8220;No Line&#8220; custom_height_tablet=&#8220;0&#8243; custom_height_phone=&#8220;0&#8243; custom_height=&#8220;75&#8243;][vc_row_inner column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; top_padding=&#8220;10%&#8220; left_padding_desktop=&#8220;2%&#8220; right_padding_desktop=&#8220;10%&#8220; top_padding_tablet=&#8220;0&#8243; top_padding_phone=&#8220;0&#8243; translate_y=&#8220;0&#8243; translate_y_tablet=&#8220;-275&#8243; translate_y_phone=&#8220;-200&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; translate_y=&#8220;-100&#8243; translate_y_tablet=&#8220;-100&#8243; translate_y_phone=&#8220;-100&#8243; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;0px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; mobile_disable_entrance_animation=&#8220;true&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220; delay=&#8220;900&#8243;][image_with_animation image_url=&#8220;2780&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; margin_bottom=&#8220;25&#8243;][vc_column_text css=&#8220;.vc_custom_1732453711327{margin-left: 35px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h3 style=\"text-align: center;\">Schlosserei und Metallbau<\/h3>\n<p>Vom einfachen Biegen und Schneiden von Metallblechen bis hin zu komplexen Strukturen: Treppen, Gel\u00e4nder, Br\u00fcstungen, Z\u00e4une, Schranken, T\u00fcren, M\u00f6bel, &#8230; wir k\u00f6nnen alles herstellen.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; translate_x=&#8220;-100&#8243; translate_x_tablet=&#8220;0&#8243; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;0px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;471&#8243; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; enable_bg_scale=&#8220;true&#8220; background_image_loading=&#8220;lazy-load&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;relative&#8220; advanced_gradient_angle=&#8220;180&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;advanced&#8220; advanced_gradient_display_type=&#8220;linear&#8220; column_padding_type=&#8220;default&#8220; offset=&#8220;vc_hidden-sm vc_hidden-xs&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; bottom_padding=&#8220;5%&#8220; translate_y_phone=&#8220;-100&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;hidden&#8220; id=&#8220;maintenanceresidence&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; translate_x=&#8220;100&#8243; translate_x_tablet=&#8220;0&#8243; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;0px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;457&#8243; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; enable_bg_scale=&#8220;true&#8220; background_image_loading=&#8220;lazy-load&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;relative&#8220; advanced_gradient_angle=&#8220;180&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;advanced&#8220; advanced_gradient_display_type=&#8220;linear&#8220; column_padding_type=&#8220;default&#8220; offset=&#8220;vc_hidden-sm vc_hidden-xs&#8220;][\/vc_column][vc_column top_padding_desktop=&#8220;4vw&#8220; bottom_padding_desktop=&#8220;6vw&#8220; left_padding_desktop=&#8220;7vw&#8220; constrain_group_101=&#8220;yes&#8220; right_padding_desktop=&#8220;7vw&#8220; translate_y_tablet=&#8220;0&#8243; translate_y_phone=&#8220;0&#8243; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.8&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;advanced&#8220;][divider line_type=&#8220;No Line&#8220; custom_height_tablet=&#8220;0&#8243; custom_height=&#8220;20&#8243;][vc_row_inner column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; top_padding=&#8220;10%&#8220; left_padding_desktop=&#8220;2%&#8220; right_padding_desktop=&#8220;10%&#8220; top_padding_tablet=&#8220;10%&#8220; top_padding_phone=&#8220;0&#8243; translate_y=&#8220;0&#8243; translate_y_tablet=&#8220;0&#8243; translate_y_phone=&#8220;-40&#8243; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; translate_y=&#8220;-100&#8243; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;0px&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; advanced_gradient_angle=&#8220;0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; mobile_disable_entrance_animation=&#8220;true&#8220; animation_easing=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; gradient_type=&#8220;default&#8220; column_padding_type=&#8220;default&#8220; delay=&#8220;900&#8243;][image_with_animation image_url=&#8220;2790&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; margin_bottom=&#8220;25&#8243;][vc_column_text css=&#8220;.vc_custom_1732399269837{margin-left: 35px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h3 style=\"text-align: center;\">Instandhaltung der Residenz<\/h3>\n<p class=\"p1\">Unsere Aufgabe ist es, die Gemeinschaftsbereiche einer Wohnanlage zu \u00fcberpr\u00fcfen und m\u00f6gliche Probleme zu erkennen. Beleuchtung, T\u00fcrfunktion, Wasseraustritt,&#8230; wir greifen nur ein, wenn es notwendig ist und auf der Grundlage eines Wartungsvertrages.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220;&#8230;<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":53,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2845","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dienste - DEN MOBILEN HANDWIERKER<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dienste - DEN MOBILEN HANDWIERKER\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/\" \/>\n<meta property=\"og:site_name\" content=\"DEN MOBILEN HANDWIERKER\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-25T17:25:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/\",\"url\":\"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/\",\"name\":\"Dienste - DEN MOBILEN HANDWIERKER\",\"isPartOf\":{\"@id\":\"https:\/\/www.denhandwierker.lu\/de\/#website\"},\"datePublished\":\"2024-11-24T12:07:20+00:00\",\"dateModified\":\"2024-11-25T17:25:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.denhandwierker.lu\/de\/den-mobilen-handwierker\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dienste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.denhandwierker.lu\/de\/#website\",\"url\":\"https:\/\/www.denhandwierker.lu\/de\/\",\"name\":\"DEN MOBILEN HANDWIERKER\",\"description\":\"Tous travaux en menuiserie, serrurerie et construction m\u00e9tallique \u00e0 Kehlen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.denhandwierker.lu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dienste - DEN MOBILEN HANDWIERKER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/","og_locale":"de_DE","og_type":"article","og_title":"Dienste - DEN MOBILEN HANDWIERKER","og_description":"[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220;...","og_url":"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/","og_site_name":"DEN MOBILEN HANDWIERKER","article_modified_time":"2024-11-25T17:25:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/","url":"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/","name":"Dienste - DEN MOBILEN HANDWIERKER","isPartOf":{"@id":"https:\/\/www.denhandwierker.lu\/de\/#website"},"datePublished":"2024-11-24T12:07:20+00:00","dateModified":"2024-11-25T17:25:04+00:00","breadcrumb":{"@id":"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.denhandwierker.lu\/de\/dienste-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.denhandwierker.lu\/de\/dienste-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.denhandwierker.lu\/de\/den-mobilen-handwierker\/"},{"@type":"ListItem","position":2,"name":"Dienste"}]},{"@type":"WebSite","@id":"https:\/\/www.denhandwierker.lu\/de\/#website","url":"https:\/\/www.denhandwierker.lu\/de\/","name":"DEN MOBILEN HANDWIERKER","description":"Tous travaux en menuiserie, serrurerie et construction m\u00e9tallique \u00e0 Kehlen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.denhandwierker.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.denhandwierker.lu\/de\/wp-json\/wp\/v2\/pages\/2845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.denhandwierker.lu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.denhandwierker.lu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.denhandwierker.lu\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.denhandwierker.lu\/de\/wp-json\/wp\/v2\/comments?post=2845"}],"version-history":[{"count":97,"href":"https:\/\/www.denhandwierker.lu\/de\/wp-json\/wp\/v2\/pages\/2845\/revisions"}],"predecessor-version":[{"id":3239,"href":"https:\/\/www.denhandwierker.lu\/de\/wp-json\/wp\/v2\/pages\/2845\/revisions\/3239"}],"wp:attachment":[{"href":"https:\/\/www.denhandwierker.lu\/de\/wp-json\/wp\/v2\/media?parent=2845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}